{"id":5655,"date":"2024-05-23T15:08:51","date_gmt":"2024-05-23T13:08:51","guid":{"rendered":"https:\/\/funandtickets.com\/tour\/private-four-hour-walking-tour-of-madrid\/"},"modified":"2026-08-16T19:06:33","modified_gmt":"2026-08-16T17:06:33","slug":"tour-privado-de-cuatro-horas-en-madrid","status":"publish","type":"portfolio","link":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/","title":{"rendered":"Tour Privado de Cuatro Horas en Madrid"},"content":{"rendered":"<p><script type=\"text\/javascript\" src=\"https:\/\/widgets.bokun.io\/assets\/javascripts\/apps\/build\/BokunWidgetsLoader.js?bookingChannelUUID=ce72115f-5b80-452f-b2ce-378df1b2cd16\" async=\"\"><\/script><\/p>\n<div class=\"bokunWidget\" data-src=\"https:\/\/widgets.bokun.io\/online-sales\/ce72115f-5b80-452f-b2ce-378df1b2cd16\/experience-calendar\/672934\"><\/div>\n<p><noscript>Please enable javascript in your browser to book<\/noscript><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo mejor de Madrid en un tour privado de cuatro horas. En este tour trataremos de mezclar lo mejor de Madrid, a menos que nos pidas que hagamos un itinerario diferente. [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/\">Leer m\u00e1s&#8230;<span class=\"screen-reader-text\"> from Tour Privado de Cuatro Horas en Madrid<\/span><\/a><\/p>\n","protected":false},"featured_media":5651,"comment_status":"closed","ping_status":"closed","template":"","portfolio_entries":[82],"portfolio_tags":[111,116],"class_list":["post-5655","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-madrid","portfolio_tags-historico-y-cultural","portfolio_tags-privado-y-grupo-reducido"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour Privado de Cuatro Horas en Madrid - Fun &amp; Tickets<\/title>\n<meta name=\"description\" content=\"Lo mejor de Madrid en un tour privado. Visitaremos lo mejor de Madrid, a menos que nos pidas que hagamos un itinerario diferente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour Privado de Cuatro Horas en Madrid - Fun &amp; Tickets\" \/>\n<meta property=\"og:description\" content=\"Lo mejor de Madrid en un tour privado. Visitaremos lo mejor de Madrid, a menos que nos pidas que hagamos un itinerario diferente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Excursiones Fun and Tickets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/funandtickets\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-16T17:06:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/funandtickets.com\/wp-content\/uploads\/2022\/02\/madrid-funandtickets.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"220\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/tour\\\/tour-privado-de-cuatro-horas-en-madrid\\\/\",\"url\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/tour\\\/tour-privado-de-cuatro-horas-en-madrid\\\/\",\"name\":\"Tour Privado de Cuatro Horas en Madrid - Fun & Tickets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/tour\\\/tour-privado-de-cuatro-horas-en-madrid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/tour\\\/tour-privado-de-cuatro-horas-en-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/funandtickets.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/madrid-funandtickets.jpg\",\"datePublished\":\"2024-05-23T13:08:51+00:00\",\"dateModified\":\"2026-08-16T17:06:33+00:00\",\"description\":\"Lo mejor de Madrid en un tour privado. Visitaremos lo mejor de Madrid, a menos que nos pidas que hagamos un itinerario diferente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/tour\\\/tour-privado-de-cuatro-horas-en-madrid\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/funandtickets.com\\\/es\\\/tour\\\/tour-privado-de-cuatro-horas-en-madrid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/tour\\\/tour-privado-de-cuatro-horas-en-madrid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/funandtickets.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/madrid-funandtickets.jpg\",\"contentUrl\":\"https:\\\/\\\/funandtickets.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/madrid-funandtickets.jpg\",\"width\":400,\"height\":220,\"caption\":\"Sol madrid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/tour\\\/tour-privado-de-cuatro-horas-en-madrid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tours\",\"item\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/tour\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tour Privado de Cuatro Horas en Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/\",\"name\":\"Excursiones Fun and Tickets\",\"description\":\"Excursiones y actividades en Madrid, Toledo, \u00c1vila, Segovia, Valle de los Ca\u00eddos, El Escorial, Alcal\u00e1 de Henares e Islas Baleares\",\"publisher\":{\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"TravelAgency\",\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/#organization\",\"name\":\"Desarrollos Turisticos S.L.\",\"alternateName\":\"Desarrollos Turisticos\",\"url\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/funandtickets.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logofunandtickets.png\",\"contentUrl\":\"https:\\\/\\\/funandtickets.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logofunandtickets.png\",\"width\":340,\"height\":156,\"caption\":\"Desarrollos Turisticos S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/funandtickets.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/funandtickets\",\"https:\\\/\\\/www.instagram.com\\\/funandtickets\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fun-and-tickets\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@funandticketstoursyexcursi4317\"],\"telephone\":\"+34912590230\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Calle Coloreros, 2\",\"addressLocality\":\"Madrid\",\"postalCode\":\"28013\",\"addressCountry\":\"ES\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":40.4164303,\"longitude\":-3.7069863},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:30\",\"closes\":\"21:00\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour Privado de Cuatro Horas en Madrid - Fun & Tickets","description":"Lo mejor de Madrid en un tour privado. Visitaremos lo mejor de Madrid, a menos que nos pidas que hagamos un itinerario diferente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"Tour Privado de Cuatro Horas en Madrid - Fun & Tickets","og_description":"Lo mejor de Madrid en un tour privado. Visitaremos lo mejor de Madrid, a menos que nos pidas que hagamos un itinerario diferente.","og_url":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/","og_site_name":"Excursiones Fun and Tickets","article_publisher":"https:\/\/www.facebook.com\/funandtickets","article_modified_time":"2026-08-16T17:06:33+00:00","og_image":[{"width":400,"height":220,"url":"https:\/\/funandtickets.com\/wp-content\/uploads\/2022\/02\/madrid-funandtickets.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/","url":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/","name":"Tour Privado de Cuatro Horas en Madrid - Fun & Tickets","isPartOf":{"@id":"https:\/\/funandtickets.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/#primaryimage"},"image":{"@id":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/funandtickets.com\/wp-content\/uploads\/2022\/02\/madrid-funandtickets.jpg","datePublished":"2024-05-23T13:08:51+00:00","dateModified":"2026-08-16T17:06:33+00:00","description":"Lo mejor de Madrid en un tour privado. Visitaremos lo mejor de Madrid, a menos que nos pidas que hagamos un itinerario diferente.","breadcrumb":{"@id":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/#primaryimage","url":"https:\/\/funandtickets.com\/wp-content\/uploads\/2022\/02\/madrid-funandtickets.jpg","contentUrl":"https:\/\/funandtickets.com\/wp-content\/uploads\/2022\/02\/madrid-funandtickets.jpg","width":400,"height":220,"caption":"Sol madrid"},{"@type":"BreadcrumbList","@id":"https:\/\/funandtickets.com\/es\/tour\/tour-privado-de-cuatro-horas-en-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/funandtickets.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tours","item":"https:\/\/funandtickets.com\/es\/tour\/"},{"@type":"ListItem","position":3,"name":"Tour Privado de Cuatro Horas en Madrid"}]},{"@type":"WebSite","@id":"https:\/\/funandtickets.com\/es\/#website","url":"https:\/\/funandtickets.com\/es\/","name":"Excursiones Fun and Tickets","description":"Excursiones y actividades en Madrid, Toledo, \u00c1vila, Segovia, Valle de los Ca\u00eddos, El Escorial, Alcal\u00e1 de Henares e Islas Baleares","publisher":{"@id":"https:\/\/funandtickets.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/funandtickets.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"TravelAgency","@id":"https:\/\/funandtickets.com\/es\/#organization","name":"Desarrollos Turisticos S.L.","alternateName":"Desarrollos Turisticos","url":"https:\/\/funandtickets.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/funandtickets.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/funandtickets.com\/wp-content\/uploads\/2018\/10\/logofunandtickets.png","contentUrl":"https:\/\/funandtickets.com\/wp-content\/uploads\/2018\/10\/logofunandtickets.png","width":340,"height":156,"caption":"Desarrollos Turisticos S.L."},"image":{"@id":"https:\/\/funandtickets.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/funandtickets","https:\/\/www.instagram.com\/funandtickets\/","https:\/\/www.linkedin.com\/company\/fun-and-tickets\/","https:\/\/www.youtube.com\/@funandticketstoursyexcursi4317"],"telephone":"+34912590230","address":{"@type":"PostalAddress","streetAddress":"Calle Coloreros, 2","addressLocality":"Madrid","postalCode":"28013","addressCountry":"ES"},"geo":{"@type":"GeoCoordinates","latitude":40.4164303,"longitude":-3.7069863},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:30","closes":"21:00"}}]}},"_links":{"self":[{"href":"https:\/\/funandtickets.com\/es\/wp-json\/wp\/v2\/portfolio\/5655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/funandtickets.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/funandtickets.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/funandtickets.com\/es\/wp-json\/wp\/v2\/comments?post=5655"}],"version-history":[{"count":0,"href":"https:\/\/funandtickets.com\/es\/wp-json\/wp\/v2\/portfolio\/5655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/funandtickets.com\/es\/wp-json\/wp\/v2\/media\/5651"}],"wp:attachment":[{"href":"https:\/\/funandtickets.com\/es\/wp-json\/wp\/v2\/media?parent=5655"}],"wp:term":[{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/funandtickets.com\/es\/wp-json\/wp\/v2\/portfolio_entries?post=5655"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/funandtickets.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=5655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}